{"id":5121,"date":"2020-05-02T12:34:38","date_gmt":"2020-05-02T10:34:38","guid":{"rendered":"https:\/\/www.onda-it.com\/?p=5121"},"modified":"2023-04-04T11:32:58","modified_gmt":"2023-04-04T09:32:58","slug":"funzionamento-scambiatori-di-calore-evaporatore-allagato-a-fascio-tubiero","status":"publish","type":"post","link":"https:\/\/www.onda-it.com\/ita\/news\/funzionamento-scambiatori-di-calore\/evaporatore-allagato-a-fascio-tubiero\/","title":{"rendered":"Evaporatore allagato a fascio tubiero"},"content":{"rendered":"<div data-wkp-cms-type=\"media\">\n<div class=\"wkp-media-element\" data-type=\"image\" data-widget=\"mediaelement\"><img decoding=\"async\" class=\" wp-image-5123 aligncenter\" src=\"https:\/\/www.onda-it.com\/wp-content\/uploads\/2022\/11\/Evaporatore-allagato-300x227.png\" alt=\"\" width=\"454\" height=\"344\" srcset=\"https:\/\/www.onda-it.com\/wp-content\/uploads\/2022\/11\/Evaporatore-allagato-300x227.png 300w, https:\/\/www.onda-it.com\/wp-content\/uploads\/2022\/11\/Evaporatore-allagato-768x582.png 768w, https:\/\/www.onda-it.com\/wp-content\/uploads\/2022\/11\/Evaporatore-allagato-350x265.png 350w, https:\/\/www.onda-it.com\/wp-content\/uploads\/2022\/11\/Evaporatore-allagato.png 888w\" sizes=\"(max-width: 454px) 100vw, 454px\" \/><\/div>\n<\/div>\n<div data-type=\"image\" data-widget=\"mediaelement\"><\/div>\n<div data-type=\"image\" data-widget=\"mediaelement\"><\/div>\n<div data-type=\"image\" data-widget=\"mediaelement\"><\/div>\n<div data-wkp-cms-type=\"media\">\n<div class=\"wkp-media-element\" data-type=\"image\" data-widget=\"mediaelement\">Negli <strong>evaporatori allagati<\/strong>, un\u00a0<strong>bagno di refrigerante<\/strong>\u00a0sommerge i tubi che si trovano nella parte inferiore del mantello.<\/div>\n<\/div>\n<div class=\"cms-block__paragraphs\" data-wkp-cms-type=\"text\">\n<p style=\"text-align: left;\">Il livello del liquido all&#8217;interno del mantello \u00e8 controllato da un sensore che mantiene i tubi costantemente bagnati dal refrigerante.<\/p>\n<p style=\"text-align: left;\">In genere il mantello \u00e8 solo parzialmente riempito di tubi, si dispone di un grande volume nella parte superiore in cui il vapore fluisce a basse velocit\u00e0 e si separa dal liquido.<\/p>\n<p style=\"text-align: left;\">Prima di uscire dallo scambiatore il vapore potr\u00e0 passare attraverso un separatore di gocce per poi andare nel compressore.<\/p>\n<p style=\"text-align: left;\">Questi evaporatori sono generalmente utilizzati con compressori senza olio ed hanno una elevata efficienza.<\/p>\n<p style=\"text-align: left;\">I vantaggi maggiori rispetto agli evaporatori ad espansione secca sono i\u00a0<strong>bassi approcci utilizzati<\/strong>\u00a0(evaporazione a 5 \u00b0C) e quindi un pi\u00f9 basso costo specifico in termini di euro\/kW.<\/p>\n<p style=\"text-align: left;\"><strong>Per avere informazioni sugli evaporatori allagati Wieland Onda clicca qui sotto :<\/strong><\/p>\n<div class=\"button-calltoaction\" style=\"text-align: left;\"><a class=\"button info\" href=\"https:\/\/www.onda-it.com\/ita\/prodotti\/scambiatori-di-calore-a-fascio-tubiero\/evaporatori-allagati-fls-flt\/\">ALLAGATI<\/a><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Negli evaporatori allagati, un\u00a0bagno di refrigerante\u00a0sommerge i tubi che si trovano nella parte inferiore del mantello.<br \/>\nIl livello del liquido all&#8217;interno del mantello \u00e8 controllato da un sensore che mantiene i tubi costantemente bagnati dal refrigerante.<br \/>\nIn genere il mantello \u00e8 solo parzialmente riempito di tubi, si dispone di un grande volume nella parte superiore in cui il vapore fluisce a basse velocit\u00e0 e si separa dal liquido.<\/p>\n","protected":false},"author":2,"featured_media":5123,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[182],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Evaporatore allagato a fascio tubiero, Funzionamento scambiatori di<\/title>\n<meta name=\"description\" content=\"Negli evaporatori allagati, un\u00a0bagno di refrigerante\u00a0sommerge i tubi che si trovano nella parte inferiore del mantello. Il livello del liquido all&#039;interno del mantello \u00e8 controllato da un sensore che mantiene i tubi costantemente bagnati dal refrigerante.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.onda-it.com\/ita\/news\/funzionamento-scambiatori-di-calore\/evaporatore-allagato-a-fascio-tubiero\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Evaporatore allagato a fascio tubiero, Funzionamento scambiatori di\" \/>\n<meta property=\"og:description\" content=\"Negli evaporatori allagati, un\u00a0bagno di refrigerante\u00a0sommerge i tubi che si trovano nella parte inferiore del mantello. Il livello del liquido all&#039;interno del mantello \u00e8 controllato da un sensore che mantiene i tubi costantemente bagnati dal refrigerante.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.onda-it.com\/ita\/news\/funzionamento-scambiatori-di-calore\/evaporatore-allagato-a-fascio-tubiero\/\" \/>\n<meta property=\"og:site_name\" content=\"Wieland Onda Srl\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-02T10:34:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-04T09:32:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.onda-it.com\/wp-content\/uploads\/2022\/11\/Evaporatore-allagato.png\" \/>\n\t<meta property=\"og:image:width\" content=\"888\" \/>\n\t<meta property=\"og:image:height\" content=\"673\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Admin Onda\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin Onda\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.onda-it.com\/ita\/news\/funzionamento-scambiatori-di-calore\/evaporatore-allagato-a-fascio-tubiero\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.onda-it.com\/ita\/news\/funzionamento-scambiatori-di-calore\/evaporatore-allagato-a-fascio-tubiero\/\"},\"author\":{\"name\":\"Admin Onda\",\"@id\":\"https:\/\/www.onda-it.com\/ita\/#\/schema\/person\/5d8361bd5e15183be56690730513a0c1\"},\"headline\":\"Evaporatore allagato a fascio tubiero\",\"datePublished\":\"2020-05-02T10:34:38+00:00\",\"dateModified\":\"2023-04-04T09:32:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.onda-it.com\/ita\/news\/funzionamento-scambiatori-di-calore\/evaporatore-allagato-a-fascio-tubiero\/\"},\"wordCount\":148,\"publisher\":{\"@id\":\"https:\/\/www.onda-it.com\/ita\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.onda-it.com\/ita\/news\/funzionamento-scambiatori-di-calore\/evaporatore-allagato-a-fascio-tubiero\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.onda-it.com\/wp-content\/uploads\/2022\/11\/Evaporatore-allagato.png\",\"articleSection\":[\"Funzionamento scambiatori di calore\"],\"inLanguage\":\"it\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.onda-it.com\/ita\/news\/funzionamento-scambiatori-di-calore\/evaporatore-allagato-a-fascio-tubiero\/\",\"url\":\"https:\/\/www.onda-it.com\/ita\/news\/funzionamento-scambiatori-di-calore\/evaporatore-allagato-a-fascio-tubiero\/\",\"name\":\"Evaporatore allagato a fascio tubiero, Funzionamento scambiatori di\",\"isPartOf\":{\"@id\":\"https:\/\/www.onda-it.com\/ita\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.onda-it.com\/ita\/news\/funzionamento-scambiatori-di-calore\/evaporatore-allagato-a-fascio-tubiero\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.onda-it.com\/ita\/news\/funzionamento-scambiatori-di-calore\/evaporatore-allagato-a-fascio-tubiero\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.onda-it.com\/wp-content\/uploads\/2022\/11\/Evaporatore-allagato.png\",\"datePublished\":\"2020-05-02T10:34:38+00:00\",\"dateModified\":\"2023-04-04T09:32:58+00:00\",\"description\":\"Negli evaporatori allagati, un\u00a0bagno di refrigerante\u00a0sommerge i tubi che si trovano nella parte inferiore del mantello. Il livello del liquido all'interno del mantello \u00e8 controllato da un sensore che mantiene i tubi costantemente bagnati dal refrigerante.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.onda-it.com\/ita\/news\/funzionamento-scambiatori-di-calore\/evaporatore-allagato-a-fascio-tubiero\/#breadcrumb\"},\"inLanguage\":\"it\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.onda-it.com\/ita\/news\/funzionamento-scambiatori-di-calore\/evaporatore-allagato-a-fascio-tubiero\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it\",\"@id\":\"https:\/\/www.onda-it.com\/ita\/news\/funzionamento-scambiatori-di-calore\/evaporatore-allagato-a-fascio-tubiero\/#primaryimage\",\"url\":\"https:\/\/www.onda-it.com\/wp-content\/uploads\/2022\/11\/Evaporatore-allagato.png\",\"contentUrl\":\"https:\/\/www.onda-it.com\/wp-content\/uploads\/2022\/11\/Evaporatore-allagato.png\",\"width\":888,\"height\":673},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.onda-it.com\/ita\/news\/funzionamento-scambiatori-di-calore\/evaporatore-allagato-a-fascio-tubiero\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.onda-it.com\/ita\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Evaporatore allagato a fascio tubiero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.onda-it.com\/ita\/#website\",\"url\":\"https:\/\/www.onda-it.com\/ita\/\",\"name\":\"Wieland Onda Srl\",\"description\":\"Wieland Onda - Advanced Heat Transfer Solution\",\"publisher\":{\"@id\":\"https:\/\/www.onda-it.com\/ita\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.onda-it.com\/ita\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.onda-it.com\/ita\/#organization\",\"name\":\"Wieland Onda Srl\",\"url\":\"https:\/\/www.onda-it.com\/ita\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it\",\"@id\":\"https:\/\/www.onda-it.com\/ita\/#\/schema\/logo\/image\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Wieland Onda Srl\"},\"image\":{\"@id\":\"https:\/\/www.onda-it.com\/ita\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/onda-s.p.a.\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.onda-it.com\/ita\/#\/schema\/person\/5d8361bd5e15183be56690730513a0c1\",\"name\":\"Admin Onda\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Evaporatore allagato a fascio tubiero, Funzionamento scambiatori di","description":"Negli evaporatori allagati, un\u00a0bagno di refrigerante\u00a0sommerge i tubi che si trovano nella parte inferiore del mantello. Il livello del liquido all'interno del mantello \u00e8 controllato da un sensore che mantiene i tubi costantemente bagnati dal refrigerante.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.onda-it.com\/ita\/news\/funzionamento-scambiatori-di-calore\/evaporatore-allagato-a-fascio-tubiero\/","og_locale":"it_IT","og_type":"article","og_title":"Evaporatore allagato a fascio tubiero, Funzionamento scambiatori di","og_description":"Negli evaporatori allagati, un\u00a0bagno di refrigerante\u00a0sommerge i tubi che si trovano nella parte inferiore del mantello. Il livello del liquido all'interno del mantello \u00e8 controllato da un sensore che mantiene i tubi costantemente bagnati dal refrigerante.","og_url":"https:\/\/www.onda-it.com\/ita\/news\/funzionamento-scambiatori-di-calore\/evaporatore-allagato-a-fascio-tubiero\/","og_site_name":"Wieland Onda Srl","article_published_time":"2020-05-02T10:34:38+00:00","article_modified_time":"2023-04-04T09:32:58+00:00","og_image":[{"width":888,"height":673,"url":"https:\/\/www.onda-it.com\/wp-content\/uploads\/2022\/11\/Evaporatore-allagato.png","type":"image\/png"}],"author":"Admin Onda","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Admin Onda","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.onda-it.com\/ita\/news\/funzionamento-scambiatori-di-calore\/evaporatore-allagato-a-fascio-tubiero\/#article","isPartOf":{"@id":"https:\/\/www.onda-it.com\/ita\/news\/funzionamento-scambiatori-di-calore\/evaporatore-allagato-a-fascio-tubiero\/"},"author":{"name":"Admin Onda","@id":"https:\/\/www.onda-it.com\/ita\/#\/schema\/person\/5d8361bd5e15183be56690730513a0c1"},"headline":"Evaporatore allagato a fascio tubiero","datePublished":"2020-05-02T10:34:38+00:00","dateModified":"2023-04-04T09:32:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.onda-it.com\/ita\/news\/funzionamento-scambiatori-di-calore\/evaporatore-allagato-a-fascio-tubiero\/"},"wordCount":148,"publisher":{"@id":"https:\/\/www.onda-it.com\/ita\/#organization"},"image":{"@id":"https:\/\/www.onda-it.com\/ita\/news\/funzionamento-scambiatori-di-calore\/evaporatore-allagato-a-fascio-tubiero\/#primaryimage"},"thumbnailUrl":"https:\/\/www.onda-it.com\/wp-content\/uploads\/2022\/11\/Evaporatore-allagato.png","articleSection":["Funzionamento scambiatori di calore"],"inLanguage":"it"},{"@type":"WebPage","@id":"https:\/\/www.onda-it.com\/ita\/news\/funzionamento-scambiatori-di-calore\/evaporatore-allagato-a-fascio-tubiero\/","url":"https:\/\/www.onda-it.com\/ita\/news\/funzionamento-scambiatori-di-calore\/evaporatore-allagato-a-fascio-tubiero\/","name":"Evaporatore allagato a fascio tubiero, Funzionamento scambiatori di","isPartOf":{"@id":"https:\/\/www.onda-it.com\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.onda-it.com\/ita\/news\/funzionamento-scambiatori-di-calore\/evaporatore-allagato-a-fascio-tubiero\/#primaryimage"},"image":{"@id":"https:\/\/www.onda-it.com\/ita\/news\/funzionamento-scambiatori-di-calore\/evaporatore-allagato-a-fascio-tubiero\/#primaryimage"},"thumbnailUrl":"https:\/\/www.onda-it.com\/wp-content\/uploads\/2022\/11\/Evaporatore-allagato.png","datePublished":"2020-05-02T10:34:38+00:00","dateModified":"2023-04-04T09:32:58+00:00","description":"Negli evaporatori allagati, un\u00a0bagno di refrigerante\u00a0sommerge i tubi che si trovano nella parte inferiore del mantello. Il livello del liquido all'interno del mantello \u00e8 controllato da un sensore che mantiene i tubi costantemente bagnati dal refrigerante.","breadcrumb":{"@id":"https:\/\/www.onda-it.com\/ita\/news\/funzionamento-scambiatori-di-calore\/evaporatore-allagato-a-fascio-tubiero\/#breadcrumb"},"inLanguage":"it","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.onda-it.com\/ita\/news\/funzionamento-scambiatori-di-calore\/evaporatore-allagato-a-fascio-tubiero\/"]}]},{"@type":"ImageObject","inLanguage":"it","@id":"https:\/\/www.onda-it.com\/ita\/news\/funzionamento-scambiatori-di-calore\/evaporatore-allagato-a-fascio-tubiero\/#primaryimage","url":"https:\/\/www.onda-it.com\/wp-content\/uploads\/2022\/11\/Evaporatore-allagato.png","contentUrl":"https:\/\/www.onda-it.com\/wp-content\/uploads\/2022\/11\/Evaporatore-allagato.png","width":888,"height":673},{"@type":"BreadcrumbList","@id":"https:\/\/www.onda-it.com\/ita\/news\/funzionamento-scambiatori-di-calore\/evaporatore-allagato-a-fascio-tubiero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.onda-it.com\/ita\/"},{"@type":"ListItem","position":2,"name":"Evaporatore allagato a fascio tubiero"}]},{"@type":"WebSite","@id":"https:\/\/www.onda-it.com\/ita\/#website","url":"https:\/\/www.onda-it.com\/ita\/","name":"Wieland Onda Srl","description":"Wieland Onda - Advanced Heat Transfer Solution","publisher":{"@id":"https:\/\/www.onda-it.com\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.onda-it.com\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it"},{"@type":"Organization","@id":"https:\/\/www.onda-it.com\/ita\/#organization","name":"Wieland Onda Srl","url":"https:\/\/www.onda-it.com\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it","@id":"https:\/\/www.onda-it.com\/ita\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Wieland Onda Srl"},"image":{"@id":"https:\/\/www.onda-it.com\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/onda-s.p.a."]},{"@type":"Person","@id":"https:\/\/www.onda-it.com\/ita\/#\/schema\/person\/5d8361bd5e15183be56690730513a0c1","name":"Admin Onda"}]}},"_links":{"self":[{"href":"https:\/\/www.onda-it.com\/ita\/wp-json\/wp\/v2\/posts\/5121"}],"collection":[{"href":"https:\/\/www.onda-it.com\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.onda-it.com\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.onda-it.com\/ita\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.onda-it.com\/ita\/wp-json\/wp\/v2\/comments?post=5121"}],"version-history":[{"count":6,"href":"https:\/\/www.onda-it.com\/ita\/wp-json\/wp\/v2\/posts\/5121\/revisions"}],"predecessor-version":[{"id":11064,"href":"https:\/\/www.onda-it.com\/ita\/wp-json\/wp\/v2\/posts\/5121\/revisions\/11064"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.onda-it.com\/ita\/wp-json\/wp\/v2\/media\/5123"}],"wp:attachment":[{"href":"https:\/\/www.onda-it.com\/ita\/wp-json\/wp\/v2\/media?parent=5121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.onda-it.com\/ita\/wp-json\/wp\/v2\/categories?post=5121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.onda-it.com\/ita\/wp-json\/wp\/v2\/tags?post=5121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}